
{"id":41952,"date":"2017-10-31T02:39:08","date_gmt":"2017-10-31T00:39:08","guid":{"rendered":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/"},"modified":"2020-05-27T17:56:24","modified_gmt":"2020-05-27T15:56:24","slug":"residential-plot-for-sale-in-agioi-omologites-nicosia","status":"publish","type":"property","link":"https:\/\/www.danos.com.cy\/el\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/","title":{"rendered":"Residential Plot for sale in Agioi Omologites Nicosia"},"content":{"rendered":"<p>LOCATION:<br \/>In Agious Omologites, Nicosia<\/p>\n<p>DESCRIPTION:<br \/>Build density: 140%<br \/>Build Coverage: 50%<br \/>Height: 17 m<br \/> Floors: 4<br \/>Zone: Ka3 <br \/> Price is estimated as a plot, although there is an old building inside.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LOCATION:In Agious Omologites, Nicosia DESCRIPTION:Build density: 140%Build Coverage: 50%Height: 17 m Floors: 4Zone: Ka3 Price is estimated as a plot, although there is an old building inside.<\/p>\n","protected":false},"author":158,"featured_media":30114,"parent":0,"menu_order":0,"template":"","property_type":[2191],"property_status":[2197],"property_feature":[],"property_label":[],"property_country":[2067],"property_state":[2072],"property_city":[2063],"property_area":[2447],"class_list":["post-41952","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-plot-el","property_status-for-sale","property_country-2067","property_state-2072","property_city-2063","property_area-2447"],"property_meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"en\":44,\"el\":44}}"],"_alp_processed":["1590594984"],"_wp_page_template":["default"],"_icl_lang_duplicate_of":["3719"],"houzez_geolocation_lat":["Agioi Omologites"],"houzez_geolocation_long":[null],"_wpml_media_has_media":["1"],"_last_translation_edit_mode":["translation-editor"],"fave_property_map":["1"],"fave_featured":["0"],"fave_agent_display_option":["agent_info"],"fave_prop_homeslider":["yes"],"fave_agents":["158"],"fave_property_map_address":[""],"fave_property_location":["Agioi Omologites"],"fave_property_price":["0000000000000000843000"],"fave_property_size":["0"],"fave_property_bedrooms":["0"],"fave_property_bathrooms":["0"],"fave_property_id":["4629"],"fave_property_map_street_view":["hide"],"fave_property_address":[""],"fave_property_agency":["-1"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"fave_property_images":["","14349","14350"],"fave_property_land":["610"],"fave_property_garage":[""],"fave_property_size_prefix":["sq.m."],"fave_property_garage_size":[""],"fave_property_year":["0"],"fave_property_sec_price":[""],"fave_property_price_postfix":[""],"fave_video_url":[""],"fave_property_zip":[""],"_thumbnail_id":["30114"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"fave_private_note":["Pikis"],"houzez_total_property_views":["483"],"houzez_views_by_date":["a:61:{s:10:\"04-15-2026\";i:2;s:10:\"04-16-2026\";i:1;s:10:\"04-18-2026\";i:1;s:10:\"04-19-2026\";i:1;s:10:\"04-20-2026\";i:1;s:10:\"04-21-2026\";i:1;s:10:\"04-24-2026\";i:1;s:10:\"04-25-2026\";i:1;s:10:\"04-26-2026\";i:1;s:10:\"04-27-2026\";i:1;s:10:\"04-28-2026\";i:1;s:10:\"04-30-2026\";i:1;s:10:\"05-03-2026\";i:1;s:10:\"05-06-2026\";i:1;s:10:\"05-07-2026\";i:3;s:10:\"05-09-2026\";i:2;s:10:\"05-10-2026\";i:1;s:10:\"05-11-2026\";i:2;s:10:\"05-13-2026\";i:2;s:10:\"05-15-2026\";i:1;s:10:\"05-16-2026\";i:1;s:10:\"05-18-2026\";i:1;s:10:\"05-19-2026\";i:3;s:10:\"05-21-2026\";i:1;s:10:\"05-23-2026\";i:1;s:10:\"05-24-2026\";i:1;s:10:\"05-25-2026\";i:1;s:10:\"05-26-2026\";i:1;s:10:\"05-27-2026\";i:2;s:10:\"05-28-2026\";i:2;s:10:\"05-30-2026\";i:2;s:10:\"06-01-2026\";i:1;s:10:\"06-02-2026\";i:1;s:10:\"06-04-2026\";i:2;s:10:\"06-05-2026\";i:1;s:10:\"06-07-2026\";i:1;s:10:\"06-08-2026\";i:1;s:10:\"06-09-2026\";i:1;s:10:\"06-11-2026\";i:1;s:10:\"06-13-2026\";i:1;s:10:\"06-16-2026\";i:2;s:10:\"06-17-2026\";i:1;s:10:\"06-18-2026\";i:1;s:10:\"06-20-2026\";i:1;s:10:\"06-21-2026\";i:2;s:10:\"06-23-2026\";i:1;s:10:\"06-24-2026\";i:1;s:10:\"06-25-2026\";i:2;s:10:\"06-26-2026\";i:1;s:10:\"06-28-2026\";i:1;s:10:\"06-30-2026\";i:1;s:10:\"07-01-2026\";i:1;s:10:\"07-02-2026\";i:1;s:10:\"07-03-2026\";i:1;s:10:\"07-04-2026\";i:1;s:10:\"07-08-2026\";i:1;s:10:\"07-09-2026\";i:1;s:10:\"07-11-2026\";i:1;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:2;s:10:\"07-15-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-15 10:09:55"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Residential Plot for sale in Agioi Omologites Nicosia - Danos | International Property Consultants &amp; Valuers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Residential Plot for sale in Agioi Omologites Nicosia - Danos | International Property Consultants &amp; Valuers\" \/>\n<meta property=\"og:description\" content=\"LOCATION:In Agious Omologites, Nicosia DESCRIPTION:Build density: 140%Build Coverage: 50%Height: 17 m Floors: 4Zone: Ka3 Price is estimated as a plot, although there is an old building inside.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/\" \/>\n<meta property=\"og:site_name\" content=\"Danos | International Property Consultants &amp; Valuers\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-27T15:56:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1509460721_129.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"991\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/\",\"url\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/\",\"name\":\"Residential Plot for sale in Agioi Omologites Nicosia - Danos | International Property Consultants &amp; Valuers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.danos.com.cy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1509460721_129.jpg\",\"datePublished\":\"2017-10-31T00:39:08+00:00\",\"dateModified\":\"2020-05-27T15:56:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.danos.com.cy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1509460721_129.jpg\",\"contentUrl\":\"https:\\\/\\\/www.danos.com.cy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1509460721_129.jpg\",\"width\":991,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/residential-plot-for-sale-in-agioi-omologites-nicosia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Residential Plot for sale in Agioi Omologites Nicosia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/\",\"name\":\"Danos | International Property Consultants &amp; Valuers\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Residential Plot for sale in Agioi Omologites Nicosia - Danos | International Property Consultants &amp; Valuers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/","og_locale":"el_GR","og_type":"article","og_title":"Residential Plot for sale in Agioi Omologites Nicosia - Danos | International Property Consultants &amp; Valuers","og_description":"LOCATION:In Agious Omologites, Nicosia DESCRIPTION:Build density: 140%Build Coverage: 50%Height: 17 m Floors: 4Zone: Ka3 Price is estimated as a plot, although there is an old building inside.","og_url":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/","og_site_name":"Danos | International Property Consultants &amp; Valuers","article_modified_time":"2020-05-27T15:56:24+00:00","og_image":[{"width":991,"height":573,"url":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1509460721_129.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/","url":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/","name":"Residential Plot for sale in Agioi Omologites Nicosia - Danos | International Property Consultants &amp; Valuers","isPartOf":{"@id":"https:\/\/www.danos.com.cy\/el\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/#primaryimage"},"image":{"@id":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1509460721_129.jpg","datePublished":"2017-10-31T00:39:08+00:00","dateModified":"2020-05-27T15:56:24+00:00","breadcrumb":{"@id":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/#primaryimage","url":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1509460721_129.jpg","contentUrl":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1509460721_129.jpg","width":991,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/www.danos.com.cy\/property\/residential-plot-for-sale-in-agioi-omologites-nicosia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.danos.com.cy\/el\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/www.danos.com.cy\/el\/property\/"},{"@type":"ListItem","position":3,"name":"Residential Plot for sale in Agioi Omologites Nicosia"}]},{"@type":"WebSite","@id":"https:\/\/www.danos.com.cy\/el\/#website","url":"https:\/\/www.danos.com.cy\/el\/","name":"Danos | International Property Consultants &amp; Valuers","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.danos.com.cy\/el\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"}]}},"_links":{"self":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties\/41952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/users\/158"}],"version-history":[{"count":1,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties\/41952\/revisions"}],"predecessor-version":[{"id":43023,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties\/41952\/revisions\/43023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/media\/30114"}],"wp:attachment":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/media?parent=41952"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_type?post=41952"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_status?post=41952"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_feature?post=41952"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_label?post=41952"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_country?post=41952"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_state?post=41952"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_city?post=41952"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_area?post=41952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}