
{"id":41913,"date":"2017-11-17T02:22:49","date_gmt":"2017-11-17T00:22:49","guid":{"rendered":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/"},"modified":"2020-05-27T17:57:08","modified_gmt":"2020-05-27T15:57:08","slug":"commercial-plot-for-sale-in-strovolos","status":"publish","type":"property","link":"https:\/\/www.danos.com.cy\/el\/property\/commercial-plot-for-sale-in-strovolos\/","title":{"rendered":"Commercial Plot for sale in Strovolos"},"content":{"rendered":"<p>LOCATION:<br \/>In Strovolos, Nicosia<\/p>\n<p>DESCRIPTION:<br \/>Build density: 120%<br \/>Build Coverage: 50%<br \/>Height: 13.5m<br \/> Floors: 3<br \/>Zone: \u00ce\u2022\u00ce\u20195<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LOCATION:In Strovolos, Nicosia DESCRIPTION:Build density: 120%Build Coverage: 50%Height: 13.5m Floors: 3Zone: \u00ce\u2022\u00ce\u20195<\/p>\n","protected":false},"author":158,"featured_media":30549,"parent":0,"menu_order":0,"template":"","property_type":[2191],"property_status":[2197],"property_feature":[],"property_label":[],"property_country":[2067],"property_state":[2072],"property_city":[2063],"property_area":[2802],"class_list":["post-41913","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-plot-el","property_status-for-sale","property_country-2067","property_state-2072","property_city-2063","property_area-2802"],"property_meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"en\":26,\"el\":26}}"],"_alp_processed":["1590595028"],"_wp_page_template":["default"],"_icl_lang_duplicate_of":["3761"],"houzez_geolocation_lat":["Strovolos Tseriou Avenue"],"houzez_geolocation_long":[null],"_wpml_media_has_media":["1"],"_last_translation_edit_mode":["translation-editor"],"fave_property_map":["1"],"fave_featured":["0"],"fave_agent_display_option":["agent_info"],"fave_prop_homeslider":["yes"],"fave_agents":["158"],"fave_property_map_address":[""],"fave_property_location":["Strovolos Tseriou Avenue"],"fave_property_price":["0000000000000000475200"],"fave_property_size":["528"],"fave_property_bedrooms":["0"],"fave_property_bathrooms":["0"],"fave_property_id":["4666"],"fave_property_map_street_view":["hide"],"fave_property_address":[""],"fave_property_agency":["-1"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"fave_property_images":["","14784","14785","14786"],"fave_property_land":["528"],"fave_property_garage":[""],"fave_property_size_prefix":["sq.m."],"fave_property_garage_size":[""],"fave_property_year":["0"],"fave_property_sec_price":[""],"fave_property_price_postfix":[""],"fave_video_url":[""],"fave_property_zip":[""],"_thumbnail_id":["30549"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"fave_private_note":["Mr Demetrios  Protopapas-99-666281"],"houzez_total_property_views":["444"],"houzez_views_by_date":["a:61:{s:10:\"04-11-2026\";i:1;s:10:\"04-12-2026\";i:1;s:10:\"04-14-2026\";i:1;s:10:\"04-15-2026\";i:1;s:10:\"04-16-2026\";i:1;s:10:\"04-17-2026\";i:3;s:10:\"04-19-2026\";i:2;s:10:\"04-21-2026\";i:1;s:10:\"04-22-2026\";i:1;s:10:\"04-24-2026\";i:1;s:10:\"04-25-2026\";i:1;s:10:\"04-26-2026\";i:1;s:10:\"04-27-2026\";i:1;s:10:\"04-28-2026\";i:1;s:10:\"04-29-2026\";i:2;s:10:\"04-30-2026\";i:1;s:10:\"05-02-2026\";i:1;s:10:\"05-04-2026\";i:1;s:10:\"05-05-2026\";i:1;s:10:\"05-06-2026\";i:1;s:10:\"05-07-2026\";i:1;s:10:\"05-09-2026\";i:1;s:10:\"05-11-2026\";i:1;s:10:\"05-13-2026\";i:1;s:10:\"05-15-2026\";i:1;s:10:\"05-16-2026\";i:1;s:10:\"05-21-2026\";i:2;s:10:\"05-22-2026\";i:1;s:10:\"05-23-2026\";i:1;s:10:\"05-25-2026\";i:1;s:10:\"05-26-2026\";i:2;s:10:\"05-30-2026\";i:1;s:10:\"05-31-2026\";i:1;s:10:\"06-02-2026\";i:1;s:10:\"06-04-2026\";i:1;s:10:\"06-05-2026\";i:2;s:10:\"06-07-2026\";i:1;s:10:\"06-08-2026\";i:1;s:10:\"06-09-2026\";i:1;s:10:\"06-10-2026\";i:1;s:10:\"06-11-2026\";i:1;s:10:\"06-13-2026\";i:1;s:10:\"06-15-2026\";i:1;s:10:\"06-17-2026\";i:2;s:10:\"06-18-2026\";i:1;s:10:\"06-20-2026\";i:1;s:10:\"06-23-2026\";i:2;s:10:\"06-25-2026\";i:1;s:10:\"06-26-2026\";i:2;s:10:\"06-27-2026\";i:1;s:10:\"06-29-2026\";i:1;s:10:\"06-30-2026\";i:1;s:10:\"07-02-2026\";i:1;s:10:\"07-05-2026\";i:1;s:10:\"07-07-2026\";i:2;s:10:\"07-08-2026\";i:1;s:10:\"07-10-2026\";i:1;s:10:\"07-12-2026\";i:1;s:10:\"07-13-2026\";i:1;s:10:\"07-14-2026\";i:1;s:10:\"07-15-2026\";i:1;}"],"houzez_recently_viewed":["2026-07-15 10:06:56"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Commercial Plot for sale in Strovolos - Danos | International Property Consultants &amp; Valuers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commercial Plot for sale in Strovolos - Danos | International Property Consultants &amp; Valuers\" \/>\n<meta property=\"og:description\" content=\"LOCATION:In Strovolos, Nicosia DESCRIPTION:Build density: 120%Build Coverage: 50%Height: 13.5m Floors: 3Zone: \u00ce\u2022\u00ce\u20195\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/\" \/>\n<meta property=\"og:site_name\" content=\"Danos | International Property Consultants &amp; Valuers\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-27T15:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1510940120_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/\",\"url\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/\",\"name\":\"Commercial Plot for sale in Strovolos - Danos | International Property Consultants &amp; Valuers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.danos.com.cy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1510940120_4.jpg\",\"datePublished\":\"2017-11-17T00:22:49+00:00\",\"dateModified\":\"2020-05-27T15:57:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.danos.com.cy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1510940120_4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.danos.com.cy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/1510940120_4.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/property\\\/commercial-plot-for-sale-in-strovolos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Commercial Plot for sale in Strovolos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/\",\"name\":\"Danos | International Property Consultants &amp; Valuers\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.danos.com.cy\\\/el\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commercial Plot for sale in Strovolos - Danos | International Property Consultants &amp; Valuers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/","og_locale":"el_GR","og_type":"article","og_title":"Commercial Plot for sale in Strovolos - Danos | International Property Consultants &amp; Valuers","og_description":"LOCATION:In Strovolos, Nicosia DESCRIPTION:Build density: 120%Build Coverage: 50%Height: 13.5m Floors: 3Zone: \u00ce\u2022\u00ce\u20195","og_url":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/","og_site_name":"Danos | International Property Consultants &amp; Valuers","article_modified_time":"2020-05-27T15:57:08+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1510940120_4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/","url":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/","name":"Commercial Plot for sale in Strovolos - Danos | International Property Consultants &amp; Valuers","isPartOf":{"@id":"https:\/\/www.danos.com.cy\/el\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/#primaryimage"},"image":{"@id":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1510940120_4.jpg","datePublished":"2017-11-17T00:22:49+00:00","dateModified":"2020-05-27T15:57:08+00:00","breadcrumb":{"@id":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/#primaryimage","url":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1510940120_4.jpg","contentUrl":"https:\/\/www.danos.com.cy\/wp-content\/uploads\/2020\/05\/1510940120_4.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.danos.com.cy\/property\/commercial-plot-for-sale-in-strovolos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.danos.com.cy\/el\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/www.danos.com.cy\/el\/property\/"},{"@type":"ListItem","position":3,"name":"Commercial Plot for sale in Strovolos"}]},{"@type":"WebSite","@id":"https:\/\/www.danos.com.cy\/el\/#website","url":"https:\/\/www.danos.com.cy\/el\/","name":"Danos | International Property Consultants &amp; Valuers","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.danos.com.cy\/el\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"}]}},"_links":{"self":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties\/41913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/users\/158"}],"version-history":[{"count":1,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties\/41913\/revisions"}],"predecessor-version":[{"id":43065,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/properties\/41913\/revisions\/43065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/media\/30549"}],"wp:attachment":[{"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/media?parent=41913"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_type?post=41913"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_status?post=41913"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_feature?post=41913"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_label?post=41913"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_country?post=41913"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_state?post=41913"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_city?post=41913"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/www.danos.com.cy\/el\/wp-json\/wp\/v2\/property_area?post=41913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}